{"id":458,"date":"2023-07-03T08:57:39","date_gmt":"2023-07-03T08:57:39","guid":{"rendered":"https:\/\/zakrademos.com\/charity\/?page_id=458"},"modified":"2026-04-29T14:28:43","modified_gmt":"2026-04-29T14:28:43","slug":"servicios","status":"publish","type":"page","link":"https:\/\/mariaolarte.com\/index.php\/servicios\/","title":{"rendered":"Servicios ofrecidos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"458\" class=\"elementor elementor-458\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-90255b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"90255b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a93e04\" data-id=\"6a93e04\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fab1d4a elementor-widget elementor-widget-heading\" data-id=\"fab1d4a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Servicios disponibles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-481eae4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"481eae4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e3267d\" data-id=\"0e3267d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7acba6e eael-product-grid-column-3 elementor-widget elementor-widget-eicon-woocommerce\" data-id=\"7acba6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eicon-woocommerce.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"eael-product-grid eael-product-simple masonry\" id=\"eael-product-grid\" data-widget-id=\"7acba6e\" data-page-id=\"458\" data-nonce=\"9d39e6a6ac\" >\n            <div class=\"woocommerce\">\n                <ul class=\"products eael-post-appender eael-post-appender-7acba6e\" data-ssi-desktop=\"no\" data-ssi-tablet=\"no\" data-ssi-mobile=\"no\" data-layout-mode=\"masonry\"> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Asesoramiento paquete AVANZADO\" loading=\"eager\" srcset=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg 1024w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-600x338.jpg 600w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-300x169.jpg 300w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"eael-product-title\">\n    <a href=\"https:\/\/mariaolarte.com\/index.php\/producto\/asesoramiento-paquete-3\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Asesoramiento paquete AVANZADO<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi>570,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/div>    \t<span id=\"woocommerce_loop_add_to_cart_link_describedby_628\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Asesoramiento paquete INTERMEDIO\" loading=\"eager\" srcset=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg 1024w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-600x338.jpg 600w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-300x169.jpg 300w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"eael-product-title\">\n    <a href=\"https:\/\/mariaolarte.com\/index.php\/producto\/asesoramiento-paquete-2\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Asesoramiento paquete INTERMEDIO<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi>380,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/div>    \t<span id=\"woocommerce_loop_add_to_cart_link_describedby_627\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li> <li class=\"product \">\n<div class=\"eael-product-wrap\" data-src=\"\" data-src-hover=\"\">\n    <img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wvs-archive-product-image\" alt=\"Asesoramiento paquete INICIAL\" loading=\"eager\" srcset=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg 1024w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-600x338.jpg 600w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-300x169.jpg 300w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><div class=\"eael-product-title\">\n    <a href=\"https:\/\/mariaolarte.com\/index.php\/producto\/album\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><h2 class=\"woocommerce-loop-product__title\">Asesoramiento paquete INICIAL<\/h2><\/a>\n    <\/div><div class=\"eael-product-price\"><span class=\"woocommerce-Price-amount amount\"><bdi>225,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\" translate=\"no\">&euro;<\/span><\/bdi><\/span><\/div>    \t<span id=\"woocommerce_loop_add_to_cart_link_describedby_586\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n    \n<\/div>\n\n<\/li><\/ul>            <\/div>\n        <\/div>\n\n        <script type=\"text\/javascript\">\n            jQuery(document).ready(function($) {\n                var $scope = jQuery(\".elementor-element-7acba6e\");\n                var $products = $('.products', $scope);\n                var $layout_mode = $products.data('layout-mode');\n                \n                if ( $layout_mode === 'masonry' ) {\n                    \/\/ init isotope\n                    var $isotope_products = $products.isotope({\n                        itemSelector: \"li.product\",\n                        layoutMode: $layout_mode,\n                        percentPosition: true\n                    });\n\n                    $isotope_products.imagesLoaded().progress( function() {\n                        $isotope_products.isotope('layout');\n                    })\n                    \n                }\n            });\n        <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eda2257 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"eda2257\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad6dda9\" data-id=\"ad6dda9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-015783d elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"015783d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65c3453\" data-id=\"65c3453\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2eb25ae elementor-widget elementor-widget-heading\" data-id=\"2eb25ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">\u00bfC\u00f3mo funciona el servicio que os ofrezco?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a83d585 elementor-widget elementor-widget-text-editor\" data-id=\"a83d585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El servicio consta de \u00abpaquetes\u00bb personalizados de asesoramiento seg\u00fan sea tu necesidad puntual.<br \/>Puedes elegir el que m\u00e1s se ajuste a tu necesidad y proyecto.<br \/>Los \u00ab<strong>paquetes<\/strong>\u00bb pueden ser <strong>modulares<\/strong>, es decir que puedes empezar con uno y luego a medida que avances puedes elegir otro para continuar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2444c09\" data-id=\"2444c09\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51819ed elementor-widget elementor-widget-image\" data-id=\"51819ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg\" class=\"attachment-large size-large wp-image-515\" alt=\"\" srcset=\"https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01.jpg 1024w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-600x338.jpg 600w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-300x169.jpg 300w, https:\/\/mariaolarte.com\/wp-content\/uploads\/2023\/03\/led01-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de61ea3 elementor-section-content-middle elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no\" data-id=\"de61ea3\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-69f1417 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"69f1417\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-718f3fc elementor-widget elementor-widget-spacer\" data-id=\"718f3fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4bcc2ac\" data-id=\"4bcc2ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6255f5d elementor-widget elementor-widget-heading\" data-id=\"6255f5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una conversaci\u00f3n de 5 minutos que puede evitarte errores y cambiar tu proyecto de bueno a excelente. \u00bfHablamos?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Servicios disponibles Asesoramiento paquete AVANZADO 570,00&nbsp;&euro; Contacta y te explico Asesoramiento paquete INTERMEDIO 380,00&nbsp;&euro; Contacta y te explico Asesoramiento paquete INICIAL 225,00&nbsp;&euro; Contacta y te explico \u00bfC\u00f3mo funciona el servicio que os ofrezco? El servicio consta de \u00abpaquetes\u00bb personalizados de asesoramiento seg\u00fan sea tu necesidad puntual.Puedes elegir el que m\u00e1s se ajuste a tu necesidad y proyecto.Los \u00abpaquetes\u00bb pueden ser modulares, es decir que puedes empezar con uno y luego a medida que avances puedes elegir otro para continuar. Una conversaci\u00f3n de 5 minutos que puede evitarte errores y cambiar tu proyecto de bueno a excelente. \u00bfHablamos?<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-458","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/pages\/458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/comments?post=458"}],"version-history":[{"count":67,"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/pages\/458\/revisions"}],"predecessor-version":[{"id":1246,"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/pages\/458\/revisions\/1246"}],"wp:attachment":[{"href":"https:\/\/mariaolarte.com\/index.php\/wp-json\/wp\/v2\/media?parent=458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}